{"id":32667,"date":"2022-08-03T13:29:19","date_gmt":"2022-08-03T17:29:19","guid":{"rendered":"https:\/\/www.cornyn.senate.gov\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/"},"modified":"2023-01-09T12:18:50","modified_gmt":"2023-01-09T17:18:50","slug":"aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver","status":"publish","type":"news","link":"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/","title":{"rendered":"Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"32667\" class=\"elementor elementor-32667 elementor-17264\" data-elementor-post-type=\"news\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23474655 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23474655\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-237e5838\" data-id=\"237e5838\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-615d862a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"615d862a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1d949cd5\" data-id=\"1d949cd5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26b0f53d breadcrumb--back elementor-widget elementor-widget-button\" data-id=\"26b0f53d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/noticias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-arrow-left\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Noticias<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27f1b0ec content-page__content\" data-id=\"27f1b0ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33e821e4 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"33e821e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42639eca elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"42639eca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a30e6e8 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"2a30e6e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAugust 3, 2022\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32cfadde elementor-share-buttons--view-icon elementor-share-buttons--skin-flat elementor-share-buttons--shape-circle elementor-share-buttons--color-custom share-buttons elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"32cfadde\" data-element_type=\"widget\" data-e-type=\"widget\" title=\"Share\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Share on email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Share on linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Share on facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9a190c callout-box elementor-widget elementor-widget-text-editor\" data-id=\"e9a190c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><em>Nueva ley inspirada por los asesinatos en una yogurter\u00eda de Austin<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8130460 elementor-widget elementor-widget-text-editor\" data-id=\"8130460\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>WASHINGTON<\/strong> &#8211; El senador John Cornyn (republicano de Texas) hizo p\u00fablica la siguiente declaraci\u00f3n despu\u00e9s de que el presidente Biden firmara la <em>Ley de Derechos de las Familias de V\u00edctimas de Homicidios<\/em>, que obliga a los organismos federales a revisar los expedientes de asesinatos sin resolver y a aplicar las nuevas tecnolog\u00edas en busca de posibles avances:  <\/p>\n<p>&#8220;<em>Esta legislaci\u00f3n contribuir\u00e1 a garantizar que las fuerzas del orden federales revisen los expedientes de casos sin resolver, que en ocasiones datan de hace d\u00e9cadas, y apliquen las \u00faltimas tecnolog\u00edas y normas de investigaci\u00f3n&#8221;<\/em>, declar\u00f3 el Senador Cornyn.  <em>&#8220;Este proceso ayudar\u00e1 a aportar a las familias en duelo una resoluci\u00f3n en medio de circunstancias tr\u00e1gicas, y estoy orgulloso del apoyo bipartidista a este proyecto de ley que ahora es ley&#8221;.  <\/em><\/p>\n<p>Los senadores Tom Cotton (R-AR), Chuck Grassley (R-IA), Dick Durbin (D-IL), Chris Coons (D-DE), Jon Ossoff (D-GA), Marsha Blackburn (R-TN), Sheldon Whitehouse (D-RI), y John Kennedy (R-LA) tambi\u00e9n copatrocinaron la legislaci\u00f3n.  <\/p>\n<p><u>Antecedentes:<\/u><\/p>\n<p>Hace m\u00e1s de 30 a\u00f1os, un cu\u00e1druple homicidio se cobr\u00f3 la vida de cuatro adolescentes en Austin (Texas) y, a d\u00eda de hoy, el caso sigue sin resolverse. La <em>Ley de Derechos de las Familias de V\u00edctimas de Homicidios <\/em>se inspir\u00f3 en este caso y exigir\u00eda a los organismos federales que examinaran los casos sin resolver con nuevos ojos y aplicaran las tecnolog\u00edas y normas de investigaci\u00f3n m\u00e1s modernas.<\/p>\n<p>El proyecto de ley tambi\u00e9n facultar\u00e1 a los familiares directos para solicitar la revisi\u00f3n de un caso sin resolver siempre que cumpla ciertos criterios b\u00e1sicos. Los organismos federales podr\u00e1n determinar si han agotado todas las pistas posibles o si la solicitud de caso sin resolver no cumple las normas para su revisi\u00f3n, y los organismos federales encargados de hacer cumplir la ley deber\u00e1n presentar informes anuales al Congreso sobre lo que funciona y lo que no funciona con las revisiones de casos sin resolver.  <\/p>\n<p>El proyecto de ley cuenta con el apoyo de la National District Attorney Association, la Federal Law Enforcement Officers Association, la National Organization for Victim Assistance, el Murder Accountability Project, la National Coalition Against Domestic Violence y otros grupos de defensa de los derechos de las v\u00edctimas.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"author":2,"template":"","news-type":[161],"issues":[177],"class_list":["post-32667","news","type-news","status-publish","hentry","news-type-press-releases-es-mx","issues-crime-law-enforcement-es-mx"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver - Senator Cornyn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver - Senator Cornyn\" \/>\n<meta property=\"og:description\" content=\"Noticias Nueva ley inspirada por los asesinatos en una yogurter\u00eda de Austin WASHINGTON &#8211; El senador John Cornyn (republicano de Texas) hizo p\u00fablica la siguiente declaraci\u00f3n despu\u00e9s de que el presidente Biden firmara la Ley de Derechos de las Familias de V\u00edctimas de Homicidios, que obliga a los organismos federales a revisar los expedientes de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/\" \/>\n<meta property=\"og:site_name\" content=\"Senator Cornyn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SenJohnCornyn\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-09T17:18:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cornyn.senate.gov\/wp-content\/uploads\/2023\/11\/Twitter-Card-Dec-23-1024x535.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@johncornyn\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/\",\"url\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/\",\"name\":\"Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver - Senator Cornyn\",\"isPartOf\":{\"@id\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/#website\"},\"datePublished\":\"2022-08-03T17:29:19+00:00\",\"dateModified\":\"2023-01-09T17:18:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/#website\",\"url\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/\",\"name\":\"Senator Cornyn\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/#organization\",\"name\":\"Senator Cornyn\",\"url\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cornyn.senate.gov\/wp-content\/uploads\/2022\/01\/Logo-2.svg\",\"contentUrl\":\"https:\/\/www.cornyn.senate.gov\/wp-content\/uploads\/2022\/01\/Logo-2.svg\",\"caption\":\"Senator Cornyn\"},\"image\":{\"@id\":\"https:\/\/www.cornyn.senate.gov\/es-mx\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SenJohnCornyn\",\"https:\/\/x.com\/johncornyn\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver - Senator Cornyn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/","og_locale":"es_MX","og_type":"article","og_title":"Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver - Senator Cornyn","og_description":"Noticias Nueva ley inspirada por los asesinatos en una yogurter\u00eda de Austin WASHINGTON &#8211; El senador John Cornyn (republicano de Texas) hizo p\u00fablica la siguiente declaraci\u00f3n despu\u00e9s de que el presidente Biden firmara la Ley de Derechos de las Familias de V\u00edctimas de Homicidios, que obliga a los organismos federales a revisar los expedientes de [&hellip;]","og_url":"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/","og_site_name":"Senator Cornyn","article_publisher":"https:\/\/www.facebook.com\/SenJohnCornyn","article_modified_time":"2023-01-09T17:18:50+00:00","og_image":[{"width":1024,"height":535,"url":"https:\/\/www.cornyn.senate.gov\/wp-content\/uploads\/2023\/11\/Twitter-Card-Dec-23-1024x535.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@johncornyn","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/","url":"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/","name":"Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver - Senator Cornyn","isPartOf":{"@id":"https:\/\/www.cornyn.senate.gov\/es-mx\/#website"},"datePublished":"2022-08-03T17:29:19+00:00","dateModified":"2023-01-09T17:18:50+00:00","breadcrumb":{"@id":"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/aprobada-una-ley-de-cornyn-para-ayudar-a-resolver-casos-sin-resolver\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cornyn.senate.gov\/es-mx\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.cornyn.senate.gov\/es-mx\/news\/"},{"@type":"ListItem","position":3,"name":"Aprobada una ley de Cornyn para ayudar a resolver casos sin resolver"}]},{"@type":"WebSite","@id":"https:\/\/www.cornyn.senate.gov\/es-mx\/#website","url":"https:\/\/www.cornyn.senate.gov\/es-mx\/","name":"Senator Cornyn","description":"","publisher":{"@id":"https:\/\/www.cornyn.senate.gov\/es-mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cornyn.senate.gov\/es-mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.cornyn.senate.gov\/es-mx\/#organization","name":"Senator Cornyn","url":"https:\/\/www.cornyn.senate.gov\/es-mx\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.cornyn.senate.gov\/es-mx\/#\/schema\/logo\/image\/","url":"https:\/\/www.cornyn.senate.gov\/wp-content\/uploads\/2022\/01\/Logo-2.svg","contentUrl":"https:\/\/www.cornyn.senate.gov\/wp-content\/uploads\/2022\/01\/Logo-2.svg","caption":"Senator Cornyn"},"image":{"@id":"https:\/\/www.cornyn.senate.gov\/es-mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SenJohnCornyn","https:\/\/x.com\/johncornyn"]}]}},"_links":{"self":[{"href":"https:\/\/www.cornyn.senate.gov\/es-mx\/wp-json\/wp\/v2\/news\/32667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cornyn.senate.gov\/es-mx\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.cornyn.senate.gov\/es-mx\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.cornyn.senate.gov\/es-mx\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/www.cornyn.senate.gov\/es-mx\/wp-json\/wp\/v2\/news\/32667\/revisions"}],"predecessor-version":[{"id":32669,"href":"https:\/\/www.cornyn.senate.gov\/es-mx\/wp-json\/wp\/v2\/news\/32667\/revisions\/32669"}],"wp:attachment":[{"href":"https:\/\/www.cornyn.senate.gov\/es-mx\/wp-json\/wp\/v2\/media?parent=32667"}],"wp:term":[{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.cornyn.senate.gov\/es-mx\/wp-json\/wp\/v2\/news-type?post=32667"},{"taxonomy":"issues","embeddable":true,"href":"https:\/\/www.cornyn.senate.gov\/es-mx\/wp-json\/wp\/v2\/issues?post=32667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}